{"id":46,"date":"2024-06-11T18:23:48","date_gmt":"2024-06-11T18:23:48","guid":{"rendered":"https:\/\/www.frydenspark.dk\/?page_id=46"},"modified":"2026-01-15T14:46:38","modified_gmt":"2026-01-15T14:46:38","slug":"om-foreningen","status":"publish","type":"page","link":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/om-foreningen\/","title":{"rendered":"Om Din Afdeling"},"content":{"rendered":"<style>.kb-row-layout-id46_b47907-87 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id46_b47907-87 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id46_b47907-87 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-5xl, 10rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_b47907-87{background-image:url('https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Website-filer\/DSC00302-scaled.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id46_b47907-87 > .kt-row-layout-overlay{opacity:0.90;background:linear-gradient(135deg,var(--global-palette1,#ffffff) 0%,var(--global-palette2,#EDF2F7) 100%);mix-blend-mode:normal;}.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id46_b47907-87 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id46_b47907-87 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id46_b47907-87 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_b47907-87 alignfull kt-row-has-bg kb-divider-static wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column46_8a52fa-e7 > .kt-inside-inner-col,.kadence-column46_8a52fa-e7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_8a52fa-e7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_8a52fa-e7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_8a52fa-e7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_8a52fa-e7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_8a52fa-e7{position:relative;}@media all and (max-width: 1024px){.kadence-column46_8a52fa-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_8a52fa-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_8a52fa-e7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e, .wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e[data-kb-block=\"kb-adv-heading46_63d3ae-0e\"]{margin-top:var(--global-kb-spacing-xs, 1rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e[data-kb-block=\"kb-adv-heading46_63d3ae-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e[data-kb-block=\"kb-adv-heading46_63d3ae-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e, .wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e[data-kb-block=\"kb-adv-heading46_63d3ae-0e\"]{font-size:60px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e, .wp-block-kadence-advancedheading.kt-adv-heading46_63d3ae-0e[data-kb-block=\"kb-adv-heading46_63d3ae-0e\"]{font-size:40px;}}<\/style>\n<h1 class=\"kt-adv-heading46_63d3ae-0e wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading46_63d3ae-0e\">Om Din Afdeling<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a, .wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a[data-kb-block=\"kb-adv-heading46_cd909c-7a\"]{display:block;text-align:center;font-size:20px;line-height:1;font-weight:300;font-style:normal;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a[data-kb-block=\"kb-adv-heading46_cd909c-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_cd909c-7a[data-kb-block=\"kb-adv-heading46_cd909c-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading46_cd909c-7a wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading46_cd909c-7a\">100 lejem\u00e5l fra 1998, af arkitekt Niels Bagger administreret af Din Boligadministration<\/span>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column46_ee5064-68 > .kt-inside-inner-col{display:flex;}.kadence-column46_ee5064-68 > .kt-inside-inner-col,.kadence-column46_ee5064-68 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_ee5064-68 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_ee5064-68 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column46_ee5064-68 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column46_ee5064-68 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column46_ee5064-68 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_ee5064-68 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_ee5064-68{position:relative;}@media all and (max-width: 1024px){.kadence-column46_ee5064-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column46_ee5064-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_ee5064-68 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><nav aria-label=\"breadcrumbs\" role=\"navigation\" class=\"surerank-breadcrumbs\"><p><span class=\"last\">Forside<\/span><\/p><\/nav>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id46_13c113-65 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_13c113-65 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_13c113-65 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_13c113-65 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46_13c113-65 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46_13c113-65 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_13c113-65 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46_2813ec-c9 > .kt-inside-inner-col,.kadence-column46_2813ec-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_2813ec-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_2813ec-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_2813ec-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_2813ec-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_2813ec-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column46_2813ec-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_2813ec-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_2813ec-c9 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Din Afdelings historie<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><em>&#8220;&#8230; Din Afdeling I Valby stod f\u00e6rdigopf\u00f8rt i september 1998.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><em>Her kan du forts\u00e6tte fort\u00e6llingen og jeres afdeling, s\u00e5 dine bes\u00f8gende kan f\u00e5 et indblik i hvordan afdelingen er udformet og hvad den indeholder.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><em>Afslut din fort\u00e6lling med et citat, en v\u00e6rdis\u00e6tning eller andet I st\u00e5r indefor.<\/em><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id46_d328e2-84 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap > *:nth-child(3n of *:not(style)){grid-column:1 \/ -1;}}@media all and (max-width: 767px){.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_d328e2-84 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_d328e2-84 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-last-row kt-mobile-layout-row kt-row-valign-middle kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column46_f1e1c7-7e > .kt-inside-inner-col,.kadence-column46_f1e1c7-7e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_f1e1c7-7e > .kt-inside-inner-col{column-gap:0px;}.kadence-column46_f1e1c7-7e > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_f1e1c7-7e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_f1e1c7-7e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_f1e1c7-7e{text-align:left;}.kadence-column46_f1e1c7-7e{position:relative;}@media all and (max-width: 1024px){.kadence-column46_f1e1c7-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_f1e1c7-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_f1e1c7-7e kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image46_b6cc1d-62 .kb-image-has-overlay:after{opacity:0.3;}.kb-image46_b6cc1d-62 img.kb-img, .kb-image46_b6cc1d-62 .kb-img img{-webkit-mask-image:url(https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/plugins\/kadence-blocks\/includes\/assets\/images\/masks\/blob1.svg);mask-image:url(https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/plugins\/kadence-blocks\/includes\/assets\/images\/masks\/blob1.svg);-webkit-mask-size:auto;mask-size:auto;-webkit-mask-repeat:no-repeat;mask-repeat:no-repeat;-webkit-mask-position:center;mask-position:center;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image46_b6cc1d-62 size-large kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land43\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Website-filer\/DSC00321-scaled-1024x576.jpg\" alt=\"DSC00321 Scaled 1024x576\" class=\"kb-img wp-image-240\" title=\"Om Din Afdeling\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column46_894e05-5f > .kt-inside-inner-col,.kadence-column46_894e05-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_894e05-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_894e05-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_894e05-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_894e05-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_894e05-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column46_894e05-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_894e05-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_894e05-5f\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box46_f19b3f-27{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_f19b3f-27{height:auto;align-self:stretch;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_f19b3f-27 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_f19b3f-27 .kt-info-svg-icon-flip, .kt-info-box46_f19b3f-27 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_f19b3f-27 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_f19b3f-27 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_f19b3f-27 .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-lg, 2rem);}.wp-block-kadence-infobox.kt-info-box46_f19b3f-27 .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_f19b3f-27 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_f19b3f-27\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Historiefort\u00e6lling 1<\/h2><p class=\"kt-blocks-info-box-text\">Kort og vigtig fort\u00e6lling fra historien, kan skrives her.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_48d2aa-66 > .kt-inside-inner-col,.kadence-column46_48d2aa-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_48d2aa-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_48d2aa-66 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_48d2aa-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_48d2aa-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_48d2aa-66{position:relative;}@media all and (max-width: 1024px){.kadence-column46_48d2aa-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_48d2aa-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_48d2aa-66\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box46_04251f-cf{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_04251f-cf{height:auto;align-self:stretch;}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_04251f-cf .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_04251f-cf .kt-info-svg-icon-flip, .kt-info-box46_04251f-cf .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_04251f-cf .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_04251f-cf .kt-blocks-info-box-media-container{margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_04251f-cf .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:var(--global-kb-font-size-md, 1.25rem);font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_04251f-cf .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_04251f-cf .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_04251f-cf .kt-infobox-textcontent h2.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-lg, 2rem);}.wp-block-kadence-infobox.kt-info-box46_04251f-cf .kt-blocks-info-box-text{font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_04251f-cf .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_04251f-cf\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\">Historiefort\u00e6lling 2<\/h2><p class=\"kt-blocks-info-box-text\">Er der noget andet som g\u00f8r Din Afdeling s\u00e6rlig unik? S\u00e5 inds\u00e6t en fort\u00e6lling mere, her.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id46_f81e0e-a5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_f81e0e-a5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_f81e0e-a5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_f81e0e-a5 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-top-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id46_f81e0e-a5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id46_f81e0e-a5 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id46_f81e0e-a5 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_f81e0e-a5 alignfull has-theme-palette8-background-color kt-row-has-bg kb-divider-static wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-top-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46_9d5072-9d > .kt-inside-inner-col,.kadence-column46_9d5072-9d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_9d5072-9d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_9d5072-9d > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_9d5072-9d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_9d5072-9d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_9d5072-9d{position:relative;}@media all and (max-width: 1024px){.kadence-column46_9d5072-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_9d5072-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_9d5072-9d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45, .wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45[data-kb-block=\"kb-adv-heading46_4e1b07-45\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45[data-kb-block=\"kb-adv-heading46_4e1b07-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45[data-kb-block=\"kb-adv-heading46_4e1b07-45\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45, .wp-block-kadence-advancedheading.kt-adv-heading46_4e1b07-45[data-kb-block=\"kb-adv-heading46_4e1b07-45\"]{font-size:var(--global-kb-font-size-md, 1.25rem);}}<\/style>\n<div class=\"kt-adv-heading46_4e1b07-45 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading46_4e1b07-45\">Ejendomskontoret<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Her er Din Afdelings ansatte<\/h2>\n\n\n<style>.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id46_9a11e0-25 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id46_9a11e0-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_9a11e0-25 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column46_162b87-87 > .kt-inside-inner-col,.kadence-column46_162b87-87 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_162b87-87 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_162b87-87 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_162b87-87 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_162b87-87 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_162b87-87{position:relative;}@media all and (max-width: 1024px){.kadence-column46_162b87-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_162b87-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_162b87-87\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_6569c2-d0.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_6569c2-d0 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_6569c2-d0 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:500px;height:0px;max-width:100%;}.kt-info-box46_6569c2-d0 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_6569c2-d0 .kt-info-svg-icon-flip, .kt-info-box46_6569c2-d0 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_6569c2-d0 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_6569c2-d0 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_6569c2-d0 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_6569c2-d0\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Niels Nielsen<\/div><p class=\"kt-blocks-info-box-text\">Ejendomsmester<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_02fb2c-8d > .kt-inside-inner-col,.kadence-column46_02fb2c-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_02fb2c-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_02fb2c-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_02fb2c-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_02fb2c-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_02fb2c-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column46_02fb2c-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_02fb2c-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_02fb2c-8d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_d03f5e-2a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_d03f5e-2a .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_d03f5e-2a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:500px;height:0px;max-width:100%;}.kt-info-box46_d03f5e-2a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_d03f5e-2a .kt-info-svg-icon-flip, .kt-info-box46_d03f5e-2a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_d03f5e-2a .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_d03f5e-2a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_d03f5e-2a .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_d03f5e-2a\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Hans Nielsen<\/div><p class=\"kt-blocks-info-box-text\">Mesterassistent<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_7d4911-29 > .kt-inside-inner-col,.kadence-column46_7d4911-29 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_7d4911-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_7d4911-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_7d4911-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_7d4911-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_7d4911-29{position:relative;}@media all and (max-width: 1024px){.kadence-column46_7d4911-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_7d4911-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_7d4911-29\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap{background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_77a531-e2.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_77a531-e2 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_77a531-e2 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:500px;height:0px;max-width:100%;}.kt-info-box46_77a531-e2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_77a531-e2 .kt-info-svg-icon-flip, .kt-info-box46_77a531-e2 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_77a531-e2 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_77a531-e2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_77a531-e2 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_77a531-e2 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_77a531-e2\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Jesper Jacobsen<\/div><p class=\"kt-blocks-info-box-text\">Ejendomsfunktion\u00e6r<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id46_de389a-2b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_de389a-2b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_de389a-2b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_de389a-2b > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep svg{fill:var(--global-palette9, #ffffff)!important;}.kb-row-layout-id46_de389a-2b .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id46_de389a-2b .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id46_de389a-2b .kt-row-layout-top-sep svg{fill:var(--global-palette9, #ffffff)!important;}@media all and (max-width: 1024px){.kb-row-layout-id46_de389a-2b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id46_de389a-2b > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id46_de389a-2b .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_de389a-2b alignfull has-theme-palette8-background-color kt-row-has-bg kb-divider-static wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-top-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-sltl\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,0l-1000,100l1000,0l0,-100Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46_a35174-51 > .kt-inside-inner-col,.kadence-column46_a35174-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_a35174-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_a35174-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_a35174-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_a35174-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_a35174-51{position:relative;}@media all and (max-width: 1024px){.kadence-column46_a35174-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_a35174-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_a35174-51\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25, .wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25[data-kb-block=\"kb-adv-heading46_d8e719-25\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25[data-kb-block=\"kb-adv-heading46_d8e719-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_d8e719-25[data-kb-block=\"kb-adv-heading46_d8e719-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading46_d8e719-25 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading46_d8e719-25\">Bestyrelsen<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Her er Din Afdelings dedikerede bestyrelse<\/h2>\n\n\n<style>.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id46_a05369-42 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id46_a05369-42 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_a05369-42 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column46_2636ee-10 > .kt-inside-inner-col,.kadence-column46_2636ee-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_2636ee-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_2636ee-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_2636ee-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_2636ee-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_2636ee-10{position:relative;}@media all and (max-width: 1024px){.kadence-column46_2636ee-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_2636ee-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_2636ee-10\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_6e7b6b-13.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_6e7b6b-13 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_6e7b6b-13 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_6e7b6b-13 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_6e7b6b-13 .kt-info-svg-icon-flip, .kt-info-box46_6e7b6b-13 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_6e7b6b-13 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_6e7b6b-13 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_6e7b6b-13 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_6e7b6b-13\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Helle Hansen<\/div><p class=\"kt-blocks-info-box-text\">Formand<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_cfe6da-5f > .kt-inside-inner-col,.kadence-column46_cfe6da-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_cfe6da-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_cfe6da-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_cfe6da-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_cfe6da-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_cfe6da-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column46_cfe6da-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_cfe6da-5f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_cfe6da-5f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_da0a8f-64.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_da0a8f-64 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_da0a8f-64 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_da0a8f-64 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_da0a8f-64 .kt-info-svg-icon-flip, .kt-info-box46_da0a8f-64 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_da0a8f-64 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_da0a8f-64 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_da0a8f-64 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_da0a8f-64\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Mik Thorsen<\/div><p class=\"kt-blocks-info-box-text\">N\u00e6stformand<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_f12459-09 > .kt-inside-inner-col,.kadence-column46_f12459-09 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_f12459-09 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_f12459-09 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_f12459-09 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_f12459-09 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_f12459-09{position:relative;}@media all and (max-width: 1024px){.kadence-column46_f12459-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_f12459-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_f12459-09\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_704818-61.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_704818-61 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_704818-61 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_704818-61 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_704818-61 .kt-info-svg-icon-flip, .kt-info-box46_704818-61 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_704818-61 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_704818-61 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_704818-61 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_704818-61 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_704818-61 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_704818-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_704818-61\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Mike Henriksen<\/div><p class=\"kt-blocks-info-box-text\">Regnskab<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_f4c5f5-45 > .kt-inside-inner-col,.kadence-column46_f4c5f5-45 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_f4c5f5-45 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_f4c5f5-45 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_f4c5f5-45 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_f4c5f5-45 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_f4c5f5-45{position:relative;}@media all and (max-width: 1024px){.kadence-column46_f4c5f5-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_f4c5f5-45 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_f4c5f5-45\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_e1184b-8e.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_e1184b-8e .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_e1184b-8e .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_e1184b-8e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_e1184b-8e .kt-info-svg-icon-flip, .kt-info-box46_e1184b-8e .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_e1184b-8e .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_e1184b-8e .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_e1184b-8e .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_e1184b-8e .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_e1184b-8e\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Muhammed El Zwhaibi<\/div><p class=\"kt-blocks-info-box-text\">Bestyrelsesmedlem<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_d923d5-27 > .kt-inside-inner-col,.kadence-column46_d923d5-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_d923d5-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_d923d5-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_d923d5-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_d923d5-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_d923d5-27{position:relative;}@media all and (max-width: 1024px){.kadence-column46_d923d5-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_d923d5-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_d923d5-27\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_be946b-11.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_be946b-11 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_be946b-11 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_be946b-11 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_be946b-11 .kt-info-svg-icon-flip, .kt-info-box46_be946b-11 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_be946b-11 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_be946b-11 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_be946b-11 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_be946b-11 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_be946b-11\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Mikkel De Voss<\/div><p class=\"kt-blocks-info-box-text\">Bestyrelsesmedlem<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_bd318f-f9 > .kt-inside-inner-col,.kadence-column46_bd318f-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_bd318f-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_bd318f-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_bd318f-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_bd318f-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_bd318f-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column46_bd318f-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_bd318f-f9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_bd318f-f9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_1fcfcd-14.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_1fcfcd-14 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_1fcfcd-14 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_1fcfcd-14 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_1fcfcd-14 .kt-info-svg-icon-flip, .kt-info-box46_1fcfcd-14 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_1fcfcd-14 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_1fcfcd-14 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1fcfcd-14 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_1fcfcd-14\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Heinrik Espersen<\/div><p class=\"kt-blocks-info-box-text\">Suppleant<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_dca7d8-c0 > .kt-inside-inner-col,.kadence-column46_dca7d8-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_dca7d8-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_dca7d8-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_dca7d8-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_dca7d8-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_dca7d8-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column46_dca7d8-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_dca7d8-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_dca7d8-c0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_1765d9-90.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_1765d9-90 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_1765d9-90 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_1765d9-90 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_1765d9-90 .kt-info-svg-icon-flip, .kt-info-box46_1765d9-90 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_1765d9-90 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_1765d9-90 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1765d9-90 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1765d9-90 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_1765d9-90\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Kasper F Timondus<\/div><p class=\"kt-blocks-info-box-text\">Suppleant<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_b699f8-88 > .kt-inside-inner-col,.kadence-column46_b699f8-88 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_b699f8-88 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_b699f8-88 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_b699f8-88 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_b699f8-88 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_b699f8-88{position:relative;}@media all and (max-width: 1024px){.kadence-column46_b699f8-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_b699f8-88 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_b699f8-88\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_1b2239-61.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_1b2239-61 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_1b2239-61 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_1b2239-61 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_1b2239-61 .kt-info-svg-icon-flip, .kt-info-box46_1b2239-61 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-media-container{margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_1b2239-61 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_1b2239-61 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_1b2239-61 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_1b2239-61 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_1b2239-61\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Anker Thuesen<\/div><p class=\"kt-blocks-info-box-text\">Suppleant<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column46_62498a-e4 > .kt-inside-inner-col,.kadence-column46_62498a-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_62498a-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_62498a-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_62498a-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_62498a-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_62498a-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column46_62498a-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_62498a-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_62498a-e4 kvs-lg-false kvs-md-false kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:0px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:var(--global-palette9, #ffffff);}.kt-info-box46_5d0272-e5.wp-block-kadence-infobox{max-width:100%;}.kt-info-box46_5d0272-e5 .kadence-info-box-image-inner-intrisic-container{max-width:2560px;}.kt-info-box46_5d0272-e5 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.33%;width:500px;height:0px;max-width:100%;}.kt-info-box46_5d0272-e5 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box46_5d0272-e5 .kt-info-svg-icon-flip, .kt-info-box46_5d0272-e5 .kt-blocks-info-box-number{font-size:40px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);}.kt-info-box46_5d0272-e5 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);font-size:20px;font-weight:300;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover div.kt-blocks-info-box-title{color:var(--global-palette1, #3182CE);}.kt-info-box46_5d0272-e5 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette6, #718096);}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}@media all and (max-width: 1024px){.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 1024px){.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}@media all and (max-width: 767px){.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}.kt-info-box46_5d0272-e5 .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 14px 0px rgba(27, 32, 44, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box46_5d0272-e5\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-port34\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg\" alt=\"Billede Paa Vej\" width=\"500\" height=\"500\" class=\"kt-info-box-image wp-image-974\" title=\"Om Din Afdeling\" srcset=\"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej.jpg 500w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-300x300.jpg 300w, https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Personale\/Billede-paa-vej-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Har I flere medlemmer?<\/div><p class=\"kt-blocks-info-box-text\">Tilf\u00f8j flere bokse nemt<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id46_e80e73-14 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id46_e80e73-14 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id46_e80e73-14 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-4xl, 8rem);padding-bottom:var(--global-kb-spacing-4xl, 8rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id46_e80e73-14{background-image:linear-gradient(135deg,var(--global-palette1,#ffffff) 41%,var(--global-palette2,#eef2f5) 100%);}.kb-row-layout-id46_e80e73-14 > .kt-row-layout-overlay{opacity:0.20;background-image:url('https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Website-filer\/DSC00308-scaled.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id46_e80e73-14 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id46_e80e73-14 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id46_e80e73-14 alignfull has-theme-palette2-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column46_f086ca-c9 > .kt-inside-inner-col,.kadence-column46_f086ca-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column46_f086ca-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column46_f086ca-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column46_f086ca-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column46_f086ca-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column46_f086ca-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column46_f086ca-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column46_f086ca-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column46_f086ca-c9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a, .wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a[data-kb-block=\"kb-adv-heading46_9ee7f6-4a\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);line-height:1;font-style:normal;text-transform:uppercase;letter-spacing:1px;}.wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a[data-kb-block=\"kb-adv-heading46_9ee7f6-4a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_9ee7f6-4a[data-kb-block=\"kb-adv-heading46_9ee7f6-4a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading46_9ee7f6-4a wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading46_9ee7f6-4a\">Vil du flytte til Din afdeling?<\/span>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90, .wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90[data-kb-block=\"kb-adv-heading46_57a130-90\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90[data-kb-block=\"kb-adv-heading46_57a130-90\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading46_57a130-90[data-kb-block=\"kb-adv-heading46_57a130-90\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading46_57a130-90 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading46_57a130-90\">Link ind til jeres administration her fra<\/h2>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns46_1267c8-35{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns46_1267c8-35 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns46_1267c8-35\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button{color:var(--global-palette9, #ffffff);border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:focus{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn46_fc5938-c7.kb-button:focus{border-top-color:var(--global-palette9, #ffffff);border-top-style:solid;border-right-color:var(--global-palette9, #ffffff);border-right-style:solid;border-bottom-color:var(--global-palette9, #ffffff);border-bottom-style:solid;border-left-color:var(--global-palette9, #ffffff);border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn46_fc5938-c7 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-true kb-btn-global-inherit wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Skriv mig op<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Om Din Afdeling 100 lejem\u00e5l fra 1998, af arkitekt Niels Bagger administreret af Din Boligadministration Din Afdelings historie &#8220;&#8230; Din Afdeling I Valby stod f\u00e6rdigopf\u00f8rt i september 1998. Her kan du forts\u00e6tte fort\u00e6llingen og jeres afdeling, s\u00e5 dine bes\u00f8gende kan f\u00e5 et indblik i hvordan afdelingen er udformet og hvad den indeholder. Afslut din fort\u00e6lling&#8230;<\/p>\n","protected":false},"author":1,"featured_media":201,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-46","page","type-page","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-content\/uploads\/Website-filer\/DSC00263-scaled-1024x576.jpg",1024,576,true],"author_info":{"display_name":"admin","author_link":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/pages\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/media\/201"}],"wp:attachment":[{"href":"https:\/\/www.demosider.fgroupmedia.dk\/boligforening-rod\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}